{"id":57098,"date":"2014-11-20T08:26:44","date_gmt":"2014-11-20T14:26:44","guid":{"rendered":"https:\/\/www.erdheim-chester.org\/estudios-y-ensayos\/"},"modified":"2026-06-30T22:33:37","modified_gmt":"2026-07-01T03:33:37","slug":"estudios-y-ensayos","status":"publish","type":"page","link":"https:\/\/www.erdheim-chester.org\/es\/estudios-y-ensayos\/","title":{"rendered":"Estudios y ensayos"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/www.erdheim-chester.org\/wp-content\/uploads\/2024\/12\/Untitled-design-96-1.png\u00bb background_position=\u00bbbottom_center\u00bb background_vertical_offset=\u00bb20%\u00bb custom_padding=\u00bb15px||15px||true|false\u00bb background_last_edited=\u00bbon|desktop\u00bb background_position_tablet=\u00bbbottom_right\u00bb background_position_phone=\u00bbcenter_right\u00bb global_module=\u00bb28071&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF90aXRsZSIsInNldHRpbmdzIjp7ImJlZm9yZSI6IiIsImFmdGVyIjoiIn19@\u00bb _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbtitle\u00bb _module_preset=\u00bbdefault\u00bb title_font=\u00bb&#8211;et_global_heading_font|300|||||||\u00bb title_text_color=\u00bb#FFFFFF\u00bb title_font_size=\u00bb40px\u00bb custom_margin=\u00bb||3px|||\u00bb title_font_size_tablet=\u00bb\u00bb title_font_size_phone=\u00bb25px\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_button button_url=\u00bbhttps:\/\/www.erdheim-chester.org\/es\/contacta-con-nosotros\/\u00bb button_text=\u00bbContacta con nosotros\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb15px\u00bb button_text_color=\u00bb#C02E43&#8243; button_bg_color=\u00bbrgba(10,22,64,0.53)\u00bb button_border_width=\u00bb0px\u00bb button_icon=\u00bb&#xe60f;||divi||400&#8243; button_icon_color=\u00bb#C02E43&#8243; button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb filter_opacity__hover_enabled=\u00bbon|hover\u00bb filter_opacity__hover=\u00bb70%\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||0px|0px|false|false\u00bb global_colors_info=\u00bb{}\u00bb locked=\u00bboff\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#F2F2F2&#8243; custom_padding=\u00bb40px|30px|40px|30px|true|false\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb box_shadow_style=\u00bbpreset2&#8243; box_shadow_vertical=\u00bb4px\u00bb box_shadow_blur=\u00bb8px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb-10px||||false|false\u00bb custom_padding=\u00bb0px||||false|false\u00bb hover_enabled=\u00bb0&#8243; border_radii=\u00bbon|20px|20px|20px|20px\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#adadad\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<div class=\"ecd-video-embed\">\n<div class=\"ecd-video-wrapper\">\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/videoseries?si=FdToivkCbdUIJikb&#038;list=PLd9i5JBvapc729BhYDkdSqc2h2ichWGYU\" title=\"Reproductor de v\u00eddeo de YouTube\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen=\"\"><\/iframe>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb||0px||false|false\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p><span>La lista de reproducci\u00f3n de YouTube de la ECDGA, <\/span><strong><span>\u00abInvestigaci\u00f3n sobre la ECD por la ECDGA\u00bb,<\/span><\/strong><span> incluye 40 v\u00eddeos en los que profesionales m\u00e9dicos debaten sobre los tratamientos, la investigaci\u00f3n y los avances en la atenci\u00f3n al paciente de la enfermedad de Erdheim-Chester (ECD).<\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/www.youtube.com\/playlist?list=PLd9i5JBvapc729BhYDkdSqc2h2ichWGYU\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbVer lista de reproducci\u00f3n\u00bb disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_bg_color=\u00bb#C02E43&#8243; button_border_radius=\u00bb8px\u00bb button_font=\u00bb|600|||||||\u00bb button_use_icon=\u00bboff\u00bb transform_translate_linked__hover=\u00bboff\u00bb custom_padding=\u00bb16px|30px|16px|30px|true|true\u00bb hover_enabled=\u00bb0&#8243; custom_css_main_element=\u00bbwidth: 100%;||text-align: center;\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover_enabled=\u00bbon|desktop\u00bb transform_translate__hover_enabled=\u00bbon|hover\u00bb transform_rotate__hover_enabled=\u00bbon|desktop\u00bb transform_skew__hover_enabled=\u00bbon|desktop\u00bb transform_origin__hover_enabled=\u00bbon|desktop\u00bb transform_translate__hover=\u00bb0px|-3px\u00bb button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#FFFFFF\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/www.erdheim-chester.org\/es\/estudios-y-ensayos\/#trials\u00bb button_text=\u00bbVer Estudios y Ensayos Abiertos\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||19px|||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_text _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>Hay ensayos\/estudios en curso en ECD que aceptan actualmente pacientes de ECD.<\/p>\n<p>Incluso si t\u00fa o tu ser querido no os encontr\u00e1is cerca de un centro de ensayos\/estudios, se os anima a ti o al m\u00e9dico tratante a que habl\u00e9is con uno de los investigadores que participan en un ensayo\/estudio antes del tratamiento. Esto te permitir\u00e1 beneficiarte de algunas de las principales investigaciones en el cambiante mundo de los <a href=\"https:\/\/www.erdheim-chester.org\/es\/tratamientos\/\">tratamientos<\/a> de la ECD. <\/p>\n<h3>Estudios<\/h3>\n<p>La investigaci\u00f3n de la ECD implica estudios observacionales y ensayos cl\u00ednicos. Los estudios observacionales no <a href=\"https:\/\/www.erdheim-chester.org\/es\/?page_id=130928\">prueban<\/a> <a href=\"https:\/\/www.erdheim-chester.org\/es\/tratamientos\/\">tratamientos<\/a>, sino que observan a los pacientes y sus resultados a lo largo del tiempo para desarrollar una hip\u00f3tesis que luego pueda probarse mediante un ensayo cl\u00ednico. Tanto los estudios observacionales como los ensayos cl\u00ednicos necesitan la participaci\u00f3n de los pacientes para llevar a cabo la investigaci\u00f3n necesaria para saber m\u00e1s <a href=\"https:\/\/www.erdheim-chester.org\/es\/acerca-de-ecd\/\">sobre la ECD<\/a>. Un registro es un tipo de estudio observacional que suele recopilar informaci\u00f3n muy detallada sobre los pacientes.   <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=\u00bbfila\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbText\u00bb _builder_version=\u00bb4.27.7&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<h3>Ensayos cl\u00ednicos<\/h3>\n<p>Actualmente hay ensayos cl\u00ednicos abiertos para el tratamiento de ECD. Las ventajas para un paciente por entrar en un ensayo incluyen: <\/p>\n<ol>\n<li>El tratamiento, o parte del mismo, puede ser gratuito para el paciente. (A veces, tambi\u00e9n pueden proporcionarse pruebas y desplazamientos durante el ensayo. Los pacientes deben preguntar siempre qu\u00e9 costes incluye el ensayo). <\/li>\n<li>Las citas de seguimiento son muy minuciosas, y los efectos secundarios se controlan y tratan de cerca. (Cuando se conocen los efectos secundarios del tratamiento, los protocolos del ensayo se establecen para tomar medidas inmediatas en caso de que se produzcan). <\/li>\n<li>A menudo, si un paciente comienza el tratamiento fuera de un ensayo con un f\u00e1rmaco concreto, puede que no re\u00fana los requisitos para entrar en un ensayo de ese tratamiento concreto m\u00e1s adelante. Por este motivo, suele ser ventajoso preguntar sobre los ensayos antes de iniciar el tratamiento. Sin embargo, se anima a cualquier paciente interesado en entrar en un ensayo a preguntar si es elegible en cualquier momento, independientemente de sus circunstancias.  <\/li>\n<\/ol>\n<p>Las ventajas para la comunidad ECD en su conjunto cuando un paciente entra en un ensayo incluyen:<\/p>\n<ol>\n<li>Los ensayos pueden conducir a la aprobaci\u00f3n de la FDA o del gobierno para el tratamiento de ECD. Con la aprobaci\u00f3n del gobierno, ser\u00e1 m\u00e1s probable que los pagadores aprueben el pago del tratamiento. <\/li>\n<li>Con un n\u00famero limitado de pacientes ECD, es muy importante que los datos sobre el tratamiento se recojan de forma centralizada para ayudar a comprender cosas como (a) lo eficaz que es el tratamiento y en qu\u00e9 circunstancias, (b) cu\u00e1nto tiempo se debe mantener a los pacientes en tratamiento, (c) qu\u00e9 indicadores existen, si los hay, de posibles problemas de tratamiento que puedan surgir, etc.   <\/li>\n<\/ol>\n<h3>M\u00e1s informaci\u00f3n sobre ensayos cl\u00ednicos<\/h3>\n<p>En Estados Unidos, los nuevos f\u00e1rmacos se prueban en ensayos cl\u00ednicos (estudios de investigaci\u00f3n) para determinar si son seguros, si pueden tratar con \u00e9xito una enfermedad concreta y cu\u00e1l debe ser la dosis sugerida. La Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA) revisa los resultados de los ensayos cl\u00ednicos para determinar si el medicamento es un tratamiento seguro y eficaz. Cuando la FDA aprueba un tratamiento para una afecci\u00f3n concreta, el acceso a ese tratamiento resulta mucho m\u00e1s f\u00e1cil para la mayor\u00eda de los pacientes. En otros pa\u00edses se utilizan procesos similares.   <\/p>\n<p>Los ensayos cl\u00ednicos son una herramienta de investigaci\u00f3n clave para avanzar en el conocimiento m\u00e9dico y la atenci\u00f3n al paciente. ECD Los ensayos cl\u00ednicos determinan si un tratamiento es seguro y eficaz para los pacientes de ECD. Los ensayos cl\u00ednicos producen los mejores datos disponibles para la toma de decisiones sanitarias.  <\/p>\n<h3>Prop\u00f3sito<\/h3>\n<p>El prop\u00f3sito de los ensayos cl\u00ednicos es probar un medicamento de forma muy detallada y de la misma manera para todos los participantes, por lo que los estudios siguen estrictos est\u00e1ndares cient\u00edficos. Estos est\u00e1ndares protegen a los pacientes y ayudan a producir resultados de estudio fiables. Un protocolo de ensayo cl\u00ednico describe qu\u00e9 tipos de pacientes pueden participar en la investigaci\u00f3n; en otras palabras, qui\u00e9n es elegible. Cada ensayo debe incluir solo a personas que se ajusten a los par\u00e1metros establecidos para ese estudio (los criterios de elegibilidad). Los criterios de elegibilidad var\u00edan de un ensayo a otro e incluyen factores como la edad del paciente, el tipo y la etapa de la enfermedad, y si el paciente ha recibido <a href=\"https:\/\/www.erdheim-chester.org\/es\/tratamientos\/\">tratamientos<\/a> espec\u00edficos o tiene otros problemas de salud.     <\/p>\n<h3>Qu\u00e9 esperar<\/h3>\n<p>Durante un ensayo cl\u00ednico, m\u00e9dicos, enfermeros, trabajadores sociales y otros proveedores de atenci\u00f3n m\u00e9dica podr\u00edan formar parte de tu equipo de tratamiento. Controlar\u00e1n tu salud de cerca. Es posible que te sometas a m\u00e1s pruebas y ex\u00e1menes m\u00e9dicos de los que tendr\u00edas si no hubieras participado en un ensayo cl\u00ednico. Algunas personas necesitar\u00e1n viajar o permanecer en hospitales para participar en los ensayos cl\u00ednicos. Actualmente se est\u00e1n realizando ensayos cl\u00ednicos de ECD en centros m\u00e9dicos y consultas m\u00e9dicas de EE. UU. y Europa. Casi siempre, los ensayos cl\u00ednicos proporcionan la medicaci\u00f3n de forma gratuita; sin embargo, el resto de la atenci\u00f3n m\u00e9dica (visitas, esc\u00e1neres, extracciones de sangre) se factura al seguro en los pa\u00edses donde la atenci\u00f3n sanitaria la paga el seguro (como en EE. UU.). Es muy poco com\u00fan que los ensayos cl\u00ednicos de ECD proporcionen apoyo financiero para el viaje y el alojamiento, por lo que se debe esperar pagarlos uno mismo o buscar ayuda de fundaciones ben\u00e9ficas.      <\/p>\n<h3>Beneficios<\/h3>\n<p>Participar en un ensayo cl\u00ednico puede tener muchos beneficios. Por ejemplo, puedes obtener acceso a nuevos <a href=\"https:\/\/www.erdheim-chester.org\/es\/tratamientos\/\">tratamientos<\/a> que no est\u00e1n ampliamente disponibles o que pueden no estar disponibles en absoluto fuera de un ensayo. Si se demuestra que un nuevo tratamiento funciona y est\u00e1s en el grupo que lo recibe, podr\u00edas ser de los primeros en beneficiarte. Tambi\u00e9n contar\u00e1s con el apoyo de un equipo de proveedores de atenci\u00f3n m\u00e9dica, que probablemente controlar\u00e1n tu salud de cerca.   <\/p>\n<h3>Ayuda a los dem\u00e1s<\/h3>\n<p>Incluso si no te beneficias directamente de los resultados del ensayo cl\u00ednico en el que participas, la informaci\u00f3n recopilada puede ayudar a otros y aumentar el conocimiento cient\u00edfico. Las personas que participan en ensayos cl\u00ednicos son vitales para el proceso de mejora de la atenci\u00f3n m\u00e9dica. Muchas personas se ofrecen como <a href=\"https:\/\/www.erdheim-chester.org\/es\/voluntario\/\">voluntarias<\/a> porque quieren ayudar a los dem\u00e1s.  <\/p>\n<h3>Los ensayos cl\u00ednicos tienen riesgos y algunos inconvenientes, como los siguientes.<\/h3>\n<ul>\n<li>Las nuevas estrategias y <a href=\"https:\/\/www.erdheim-chester.org\/es\/tratamientos\/\">tratamientos<\/a> que se est\u00e1n estudiando no siempre son mejores que el est\u00e1ndar de atenci\u00f3n actual.<\/li>\n<li>Aunque un nuevo enfoque beneficie a algunos participantes, puede que no funcione para ti.<\/li>\n<li>Un tratamiento nuevo puede tener efectos secundarios o riesgos que los m\u00e9dicos no conocen o no esperan.<\/li>\n<li>Los seguros de salud y los proveedores no suelen cubrir los costes de la atenci\u00f3n al paciente en los ensayos cl\u00ednicos. Si est\u00e1s considerando participar en un ensayo cl\u00ednico, inf\u00f3rmate con antelaci\u00f3n sobre los costes y la cobertura del tratamiento y el viaje al centro m\u00e9dico. <\/li>\n<\/ul>\n<p>Debes informarte sobre los riesgos y beneficios de cualquier ensayo cl\u00ednico antes de aceptar participar en \u00e9l. Habla con tu m\u00e9dico sobre los ensayos espec\u00edficos que te interesan. <\/p>\n<p>Una vez que la FDA est\u00e1 convencida de que el medicamento funciona y es seguro, elabora junto con el fabricante un informe denominado etiqueta del medicamento. Este informe proporciona informaci\u00f3n muy espec\u00edfica sobre el medicamento. La FDA aprueba el informe (etiqueta), que proporciona la informaci\u00f3n necesaria a los profesionales sanitarios que recetan o venden el f\u00e1rmaco.  <\/p>\n<h3>Uso de medicamentos fuera de lo indicado<\/h3>\n<p>En EE.UU., cuando un medicamento se utiliza de forma distinta a la descrita en la etiqueta del f\u00e1rmaco aprobada por la FDA, se dice que es un uso \u00abno contemplado\u00bb. Esto puede significar que el f\u00e1rmaco <\/p>\n<ul>\n<li>Se utiliza para una enfermedad o afecci\u00f3n m\u00e9dica diferente<\/li>\n<li>Dado de forma diferente (por ejemplo, por una ruta diferente)<\/li>\n<li>Administrado en una dosis diferente a la de la etiqueta aprobada<\/li>\n<\/ul>\n<p>Algunos <a href=\"https:\/\/www.erdheim-chester.org\/es\/tratamientos\/\">tratamientos<\/a> para la ECD est\u00e1n aprobados por la FDA y otros no. Los que no est\u00e1n aprobados para la ECD se consideran de uso fuera de indicaci\u00f3n (off-label). Los <a href=\"https:\/\/www.erdheim-chester.org\/es\/tratamientos\/\">tratamientos<\/a> fuera de indicaci\u00f3n para la ECD son <a href=\"https:\/\/www.erdheim-chester.org\/es\/tratamientos\/\">tratamientos<\/a> que est\u00e1n aprobados para su uso en otras enfermedades pero no est\u00e1n aprobados para el tratamiento de la ECD. Esto es legal en los Estados Unidos y en muchos otros pa\u00edses. El uso de f\u00e1rmacos fuera de indicaci\u00f3n es com\u00fan en el tratamiento de enfermedades raras.    <\/p>\n<p>El mayor problema del uso de f\u00e1rmacos fuera de indicaci\u00f3n es obtener la aprobaci\u00f3n de un pagador (compa\u00f1\u00eda de seguros) para el reembolso de dicho uso. Muchas compa\u00f1\u00edas de seguros no pagar\u00e1n por un f\u00e1rmaco costoso que se utiliza de una manera que no figura en la etiqueta aprobada del f\u00e1rmaco. Lo hacen bas\u00e1ndose en que su uso es \u201cexperimental\u201d o \u201cde investigaci\u00f3n\u201d. Esta carga financiera puede suponer un enorme esfuerzo para los pacientes y las familias, especialmente cuando el coste de los <a href=\"https:\/\/www.erdheim-chester.org\/es\/tratamientos\/\">tratamientos<\/a> fuera de indicaci\u00f3n es muy elevado.   <\/p>\n<p>En el tratamiento del c\u00e1ncer, estas cuestiones se han abordado en gran medida mediante la legislaci\u00f3n federal de 1993, que obliga a los seguros a cubrir las terapias contra el c\u00e1ncer m\u00e9dicamente apropiadas. Esta ley incluye los usos no indicados en la etiqueta si el tratamiento se ha probado en estudios de investigaci\u00f3n minuciosos y se ha descrito en libros de referencia sobre medicamentos o en revistas m\u00e9dicas de prestigio. En 2008, se modificaron las normas de Medicare para cubrir m\u00e1s usos no indicados de f\u00e1rmacos para el tratamiento del c\u00e1ncer.  <\/p>\n<p>Aun as\u00ed, las leyes y normativas de cobertura de los seguros m\u00e9dicos son complejas. Si tu m\u00e9dico est\u00e1 considerando el uso de un f\u00e1rmaco fuera de indicaci\u00f3n, t\u00fa y tu m\u00e9dico deb\u00e9is comprobar cuidadosamente la cobertura de tu plan de salud. Los distintos pagadores de seguros tienen enfoques diferentes para el pago de medicamentos fuera de indicaci\u00f3n y aprobar\u00e1n o denegar\u00e1n las solicitudes bas\u00e1ndose en conjuntos de requisitos que variar\u00e1n de un seguro a otro. Si se te deniega la cobertura, podr\u00eda ayudar que el m\u00e9dico env\u00ede al asegurador copias de art\u00edculos de revistas revisadas por expertos u otras fuentes respetadas que respalden el uso fuera de indicaci\u00f3n. La ECD Global Alliance se complace en ayudar a los equipos m\u00e9dicos con esto. (Consulta nuestra p\u00e1gina <a href=\"https:\/\/www.erdheim-chester.org\/es\/presentar-recursos-contra-el-pagador\/\">Presentaci\u00f3n de apelaciones al pagador<\/a>).     <\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong>\u00daltima actualizaci\u00f3n:<\/strong> 17\/03\/2026<\/p>\n<p>[\/et_pb_text][et_pb_text module_id=\u00bbtrials\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Estudios y ensayos actuales abiertos ECD <\/h2>\n<div class=\"tp-sticky-wrap\">\n\n<table id=\"tablepress-1\" class=\"tablepress tablepress-id-1 tablepress-responsive tablepress-responsive-stack-headers tablepress-responsive-stack-phone\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\"><strong>#<\/strong><\/th><th class=\"column-2\"><strong>NCT#<\/strong><\/th><th class=\"column-3\"><strong>Name of Study<\/strong><\/th><th class=\"column-4\"><strong>Purpose<\/strong><\/th><th class=\"column-5\"><strong>Type of Study<\/strong><\/th><th class=\"column-6\"><strong>Selection<\/strong><\/th><th class=\"column-7\"><strong>Age Requirement<\/strong><\/th><th class=\"column-8\"><strong>Care Center \/ Contact<\/strong><\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\"><a href=\"https:\/\/classic.clinicaltrials.gov\/ct2\/show\/NCT05915208?id=NCT05915208&#038;draw=2&#038;rank=1\"target=\"_blank\">NCT05915208<\/a><\/td><td class=\"column-3\">Histiocytic Disorder Follow-up Study<\/td><td class=\"column-4\">To understand the health problems experienced by individuals with ECD and other histiocytic disorders.<\/td><td class=\"column-5\">Surveys only<br \/>\nObservational<br \/>\nRetrospective<\/td><td class=\"column-6\">English survey completion (online, on phone, or on paper) from the comfort of your home.<\/td><td class=\"column-7\">18 \u2013 89 years old<\/td><td class=\"column-8\">University of Alabama at Birmingham<br \/>\nBirmingham, AL  USA<br \/>\nGaurav Goyal, MD<br \/>\nhistio@uabmc.edu<br \/>\n+1-866-438-1640<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\"><a href=\"https:\/\/classic.clinicaltrials.gov\/ct2\/show\/NCT03329274?id=NCT03329274&#038;draw=2&#038;rank=1\"target=\"_blank\">NCT03329274<\/a><\/td><td class=\"column-3\">Registry for Patients with Erdheim-Chester Disease and Other Histiocytoses<\/td><td class=\"column-4\">Determine what kinds of health problems are caused by histiocytosis, what happens as a result of different treatments, and how ECD affects people's lives, their feelings and their attitudes.<\/td><td class=\"column-5\">Surveys &amp; medical records<br \/>\nObservational<br \/>\nProspective<\/td><td class=\"column-6\">Erdheim-Chester Disease, Langerhans cell histiocytosis, Rosai Dorfman disease, or another histiocytic neoplasm<\/td><td class=\"column-7\">18 years and older<\/td><td class=\"column-8\">MSKCC<br \/>\nNew York City, NY  USA<br \/>\nEli Diamond, MD<br \/>\ndiamone1@mskcc.org<br \/>\n+1- 212-610-0243<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\"><a href=\"https:\/\/classic.clinicaltrials.gov\/ct2\/show\/NCT03990428?id=NCT03990428&#038;draw=2&#038;rank=1\"target=\"_blank\">NCT03990428<\/a><\/td><td class=\"column-3\">Supportive Care Needs of Caregivers of People with Erdheim-Chester Disease and Other Histiocytic Diseases<\/td><td class=\"column-4\">Determine the supportive care needs of informal caregivers of people with Erdheim-Chester disease and other histiocytic diseases<\/td><td class=\"column-5\">Online surveys<br \/>\nObservational<br \/>\nProspective<\/td><td class=\"column-6\">Self id\u2019d unpaid support person for ECD, LCH, RDD, or JXG patient<\/td><td class=\"column-7\">18 years and older<\/td><td class=\"column-8\">MSKCC<br \/>\nNew York City, NY  USA<br \/>\nEli Diamond, MD<br \/>\ndiamone1@mskcc.org<br \/>\n+1- 212-610-0243<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\"><a href=\"https:\/\/classic.clinicaltrials.gov\/ct2\/show\/NCT03017820?id=NCT03017820&#038;draw=2&#038;rank=1\"target=\"_blank\">NCT03017820<\/a><\/td><td class=\"column-3\">VSV-hIFNbeta-NIS in Treating Patients With Relapsed or Refractory Multiple Myeloma, Acute Myeloid Leukemia or Lymphoma<\/td><td class=\"column-4\">Studies the best dose and side effects of recombinant vesicular stomatitis virus carrying the human NIS and IFN beta genes as a way to to kill cancer cells without damaging normal cells.  For patients whose prior treatment did not help<\/td><td class=\"column-5\">Clinical Trial<br \/>\nInterventional Treatment<\/td><td class=\"column-6\">Relapsed\/ refractory to prior ECD treatments<\/td><td class=\"column-7\">18 years and older<\/td><td class=\"column-8\">Mayo Clinic in Rochester<br \/>\nRochester, MN  USA<br \/>\nNora Bennani, MD<br \/>\nRonald Go, MD<br \/>\ngo.ronald@mayo.edu<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\"><a href=\"https:\/\/clinicaltrials.gov\/study\/NCT06712810?cond=Histiocytosis&amp;aggFilters=status:rec,studyType:int&amp;limit=100&amp;rank=41\" target=\"_blank\">NCT06712810<\/a><\/td><td class=\"column-3\">Q702 for the treatment of patients with hematologic malignancies<\/td><td class=\"column-4\">Evaluates the side effects and best dose of Q702 for patients whose prior treatment did not help.<\/td><td class=\"column-5\">Clinical Trial<br \/>\nInterventional Treatment<\/td><td class=\"column-6\">Erdheim-Chester Disease, Langerhans cell histiocytosis, Rosai Dorfman disease, or another histiocytic neoplasm<\/td><td class=\"column-7\">18 years and older<\/td><td class=\"column-8\">Mayo Clinic, Rochester, MN USA<br \/>\nJithma Abeykoon, MD<br \/>\nAbeykoon.jithma@mayo.edu<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">6<\/td><td class=\"column-2\"><a href=\"https:\/\/classic.clinicaltrials.gov\/ct2\/show\/NCT04640779?id=NCT04640779&#038;draw=2&#038;rank=1\"target=\"_blank\">NCT04640779<\/a><\/td><td class=\"column-3\">Low-Dose Selinexor and Choline Salicylate for Non-Hodgkin or Hodgkin Lymphoma, Histiocytic\/Dendritic Cell Neoplasm, or Relapsed or Refractory Multiple Myeloma<\/td><td class=\"column-4\">Evaluates the side effects and best dose of choline salicylate given together for patients whose prior treatment did not help.<\/td><td class=\"column-5\">Clinical Trial<br \/>\nInterventional Treatment<\/td><td class=\"column-6\">Relapsed\/ refractory to prior ECD treatments<\/td><td class=\"column-7\">18 years and older<\/td><td class=\"column-8\">Mayo Clinic in Rochester<br \/>\nRochester, MN  USA<br \/>\nJonas Paludo, M.D.   <br \/>\nRonald Go, MD<br \/>\ngo.ronald@mayo.edu<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">7<\/td><td class=\"column-2\"><a href=\"https:\/\/classic.clinicaltrials.gov\/ct2\/show\/NCT06153173?id=NCT06153173&#038;draw=2&#038;rank=1\"target=\"_blank\">NCT06153173<\/a><\/td><td class=\"column-3\">Mirdametinib in Histiocytic Disorders<\/td><td class=\"column-4\">Determine if treatment with mirdametinib in patients with histiocytic disorders will be better than current treatments and with fewer side effects.<\/td><td class=\"column-5\">Clinical Trial<br \/>\nInterventional Treatment<\/td><td class=\"column-6\">Diagnosis of histiocytic neoplasm confirmed by a Cincinnati Children's Hospital pathologist. Exception for those with isolated pituitary\/CNS disease where biopsy is not feasible.<\/td><td class=\"column-7\">2 years and older<\/td><td class=\"column-8\">Children's Hospital Medical Center<br \/>\nCincinnati, Ohio  USA<br \/>\nMonica Trapp<br \/>\nmonica.trapp@cchmc.org<br \/>\nAshish Kumar, MD, PhD<br \/>\n+1-513-803-8574<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">8<\/td><td class=\"column-2\"><a href=\"https:\/\/clinicaltrials.gov\/study\/NCT06411821?intr=ulixertinib&#038;rank=1\"target=\"_blank\">NCT06411821<\/a><\/td><td class=\"column-3\">Phase 2 Trial of Ulixertinib for Patients with Histiocytic Neoplasms<\/td><td class=\"column-4\">Clinical trial of oral ERK inhibitor<\/td><td class=\"column-5\">Clinical Trial<br \/>\nInterventional Treatment<\/td><td class=\"column-6\">Any histiocytic neoplasm<\/td><td class=\"column-7\">18 years and older<\/td><td class=\"column-8\">MSKCC<br \/>\nNYC, NY  USA<br \/>\nEli  Diamond, MD <br \/>\ndiamone1@mskcc.org<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">9<\/td><td class=\"column-2\"><a href=\"https:\/\/clinicaltrials.gov\/study\/NCT04079179?id=NCT04079179&#038;rank=1\"target=\"_blank\">NCT04079179<\/a><\/td><td class=\"column-3\">Cobimetinib in Refractory Langerhans Cell Histiocytosis (LCH), and Other Histiocytic Disorders (NACHO-COBI)<\/td><td class=\"column-4\">Study of cobimetinib in children and adults with LCH and other histiocytic diorders.<\/td><td class=\"column-5\">Clinical Trial<br \/>\nInterventional Treatment<\/td><td class=\"column-6\">Relapsed\/ refractory to prior ECD treatments<\/td><td class=\"column-7\">6 months and older<\/td><td class=\"column-8\">NACHO (Baltimore, Dallas, DC, Houston, Madison, Memphis, Orange, ??)<br \/>\nTexas Children\u2019s Hospital<br \/>\nHouston, TX  USA<br \/>\nCarl Allen, MD  <br \/>\nceallen@texaschildrens.org<br \/>\n+1-832-822-4242<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">10<\/td><td class=\"column-2\"><a href=\"https:\/\/clinicaltrials.gov\/study\/NCT05768178?term=NCT05768178&#038;rank=1\"target=\"_blank\">NCT05768178<\/a><\/td><td class=\"column-3\">Vemurafenib in Combination With Cobimetinib in Adult Patients With BRAF Positive Cancers.<\/td><td class=\"column-4\">Evaluate the efficacy of vemurafenib and cobimetinib in adult patients with rare cancers with BRAF V600 mutations.<\/td><td class=\"column-5\">Clinical Trial<br \/>\nInterventional Treatment<\/td><td class=\"column-6\">BRAF V600E<\/td><td class=\"column-7\">16 years and older<\/td><td class=\"column-8\">Multiple UK Hospitals<br \/>\nIncluding Leeds General Infirmary<br \/>\nLeeds, UK<br \/>\nMartin Elliott, MBBS<br \/>\nMartin.elliott1@nhs.net<br \/>\n0113 392 8779<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">11<\/td><td class=\"column-2\"><a href=\"https:\/\/clinicaltrials.gov\/search?cond=Histiocytosis&amp;aggFilters=status:rec,studyType:int&amp;limit=100\" target=\"_blank\">NCT04943198<\/a><\/td><td class=\"column-3\">Optimization of the time and dosage of vemurafenib in BRAF+ juvenile patients with refractory histiocytosis<\/td><td class=\"column-4\">Determine the optimal dosing of vemurafenib<\/td><td class=\"column-5\">Clinical Trial<\/td><td class=\"column-6\">BRAF-mutated histiocytic neoplasms relapsed\/refractory to prior treatments<\/td><td class=\"column-7\">1-18 years<\/td><td class=\"column-8\">Warsaw, Poland<br \/>\nKatarzyna Maleszewska<br \/>\nPhone Number:\u00a0+48 22 32 77 205<br \/>\nEmail Address:\u00a0klinika.onkologii@imid.med.pl<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">12<\/td><td class=\"column-2\"><a href=\"https:\/\/clinicaltrials.gov\/study\/NCT04943224?cond=Histiocytosis&amp;aggFilters=status:rec,studyType:int&amp;limit=100&amp;rank=2\" target=\"_blank\">NCT04943224<\/a><\/td><td class=\"column-3\">Optimization of the time and dosage of trametinib in BRAF negative juvenile patients<\/td><td class=\"column-4\">Determine the optimal dosing of trametinib<\/td><td class=\"column-5\">Clinical Trial<\/td><td class=\"column-6\">BRAF-unmutated histiocytic neoplasms or relapsed\/refractory BRAF-mutated previously treated with vemurafenib<\/td><td class=\"column-7\">1-18 years<\/td><td class=\"column-8\">Warsaw, Poland<br \/>\nKatarzyna Maleszewska<br \/>\nPhone Number:\u00a0+48 22 32 77 205<br \/>\nEmail Address:\u00a0klinika.onkologii@imid.med.pl<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-1 from cache -->\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La lista de reproducci\u00f3n de YouTube de la ECDGA, \u00abInvestigaci\u00f3n sobre la ECD por la ECDGA\u00bb, incluye 40 v\u00eddeos en los que profesionales m\u00e9dicos debaten sobre los tratamientos, la investigaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","cybocfi_hide_featured_image":"","footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-57098","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.erdheim-chester.org\/es\/wp-json\/wp\/v2\/pages\/57098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erdheim-chester.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.erdheim-chester.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.erdheim-chester.org\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.erdheim-chester.org\/es\/wp-json\/wp\/v2\/comments?post=57098"}],"version-history":[{"count":7,"href":"https:\/\/www.erdheim-chester.org\/es\/wp-json\/wp\/v2\/pages\/57098\/revisions"}],"predecessor-version":[{"id":166574,"href":"https:\/\/www.erdheim-chester.org\/es\/wp-json\/wp\/v2\/pages\/57098\/revisions\/166574"}],"wp:attachment":[{"href":"https:\/\/www.erdheim-chester.org\/es\/wp-json\/wp\/v2\/media?parent=57098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}